{"id":34522,"date":"2022-09-19T14:58:21","date_gmt":"2022-09-19T12:58:21","guid":{"rendered":"https:\/\/www.snccsa.com\/?p=34522"},"modified":"2022-09-19T15:39:36","modified_gmt":"2022-09-19T13:39:36","slug":"sncc-mobirail-offre-64-places-supplementaires-pour-le-train","status":"publish","type":"post","link":"https:\/\/www.snccsa.com\/en\/2022\/09\/19\/sncc-mobirail-offre-64-places-supplementaires-pour-le-train\/","title":{"rendered":"SNCC: MOBIRAIL offre 64 places suppl\u00e9mentaires pour le train de Kananga"},"content":{"rendered":"\n<p>Soucieuse de satisfaire la demande de plus en plus forte de la client\u00e8le de train voyageurs, la Direction G\u00e9n\u00e9rale de la SNCC vient d&#8217;autoriser l&#8217;augmentation de la capacit\u00e9 du train NEW EXPRESS COLOMBE( NEXCO ) pour son prochain voyage \u00e0 destination de KANANGA. Ainsi, MOBIRAIL, la Direction en charge du trafic voyageurs aligne une voiture de 2\u00e8me classe de 64 places \u00e0 si\u00e8ges , en plus de 192 places offertes habituellement \u00e0 bord de 7 voitures \u00e0 voyageurs de 1\u00e8re classe \u00e0 couchettes. Soit un total de 256 places au lieu de 192 places.<\/p>\n\n\n\n<p>La SNCC r\u00e9pond ainsi aux besoins exprim\u00e9s par sa client\u00e8le en cette p\u00e9riode de la rentr\u00e9e des classes, marqu\u00e9e particuli\u00e8rement par la raret\u00e9 des vols de compagnies d&#8217;avion entre Lubumbashi et le grand kasai.<\/p>\n\n\n\n\n\n<p>La voiture 190-9 de 2\u00e8me classe \u00e0 si\u00e8ges qui vient d&#8217; \u00eatre align\u00e9e fait partie des 12 voitures \u00e0 voyageurs neuves de la deuxi\u00e8me rame acquise par la SNCC,lesquelles seront mises en exploitation bient\u00f4t. Le d\u00e9part de LUBUMBASHI du prochain train est pr\u00e9vu le mercredi 21 septembre 2022 \u00e0 8H00 avec 8 voitures \u00e0 voyageurs, une voiture restaurant de 66 places, un fourgon \u00e0 bagages et une voiture \u00e0 g\u00e9n\u00e9rateurs.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Soucieuse de satisfaire la demande de plus en plus forte de la client\u00e8le de train voyageurs, la Direction G\u00e9n\u00e9rale de la SNCC vient d&#8217;autoriser l&#8217;augmentation de la capacit\u00e9 du train NEW EXPRESS COLOMBE( NEXCO ) pour son prochain voyage \u00e0 destination de KANANGA. Ainsi, MOBIRAIL, la Direction en charge du trafic voyageurs aligne une voiture [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25005,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-34522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/posts\/34522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/comments?post=34522"}],"version-history":[{"count":3,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/posts\/34522\/revisions"}],"predecessor-version":[{"id":34553,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/posts\/34522\/revisions\/34553"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/media\/25005"}],"wp:attachment":[{"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/media?parent=34522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/categories?post=34522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/tags?post=34522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}