{"id":67649,"date":"2023-03-07T16:47:58","date_gmt":"2023-03-07T14:47:58","guid":{"rendered":"https:\/\/www.snccsa.com\/?p=67649"},"modified":"2023-03-07T17:44:25","modified_gmt":"2023-03-07T15:44:25","slug":"sncc-pour-la-protection-des-acheminements-contre-les-intemperies","status":"publish","type":"post","link":"https:\/\/www.snccsa.com\/en\/2023\/03\/07\/sncc-pour-la-protection-des-acheminements-contre-les-intemperies\/","title":{"rendered":"Sncc: pour la protection efficace des acheminements contre les pertes et les intemp\u00e9ries"},"content":{"rendered":"<p>Il est bon que toute rame de trains marchandises soit d\u00e9sormais reconnue par la qualit\u00e9 de b\u00e2ches dont les wagons sont couverts \u00e0 savoir b\u00e2ches de couleur Bleue, num\u00e9rot\u00e9s et avec logo SNCC en blanc.<div id=\"attachment_67652\" style=\"width: 310px\"  class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.snccsa.com\/wp-content\/uploads\/2023\/03\/Videoframe_20230307_164508_com.huawei.himovie.overseas.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.snccsa.com\/wp-content\/uploads\/2023\/03\/Videoframe_20230307_164508_com.huawei.himovie.overseas-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" class=\"size-medium wp-image-67652\" \/><\/a><p class=\"wp-caption-text\">wagons bach\u00e9s<\/p><\/div><br \/>\n Comme voulu par le Directeur G\u00e9n\u00e9ral de la SNCC , M. Fabien Mutomb Kan kato, ces b\u00e2ches l\u00e0 sont d\u00e9j\u00e0 visibles lors des acheminements des frets sur ou dans des wagons ouverts. En effet Un lot de 35 <strong>b\u00e2ches REUTILISABLES DE PROTECTION <\/strong> ont \u00e9t\u00e9 livr\u00e9es depuis peu, par les services des approvisionnements aux magasins commerciaux de Lubumbashi. <a href=\"https:\/\/www.snccsa.com\/wp-content\/uploads\/2023\/03\/Videoframe_20230307_164257_com.huawei.himovie.overseas.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.snccsa.com\/wp-content\/uploads\/2023\/03\/Videoframe_20230307_164257_com.huawei.himovie.overseas-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" class=\"aligncenter size-medium wp-image-67653\" \/><\/a><br \/>\nLe Manager du chemin de fer congolais, soucieux de voir la SNCC.SA prot\u00e9ger efficacement ses convois contre les pertes et les intemp\u00e9ries, a \u00e9galement instruit la dotation en urgence d&#8217;un autre lot de 30 b\u00e2ches et des cordes. <a href=\"https:\/\/www.snccsa.com\/wp-content\/uploads\/2023\/03\/Videoframe_20230307_164427_com.huawei.himovie.overseas.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.snccsa.com\/wp-content\/uploads\/2023\/03\/Videoframe_20230307_164427_com.huawei.himovie.overseas-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" class=\"aligncenter size-medium wp-image-67654\" \/><\/a>Cette dotation est justifi\u00e9e par la demande de plus en plus forte en wagons, cons\u00e9cutive au programme lanc\u00e9 d\u00e9but f\u00e9vrier et visant \u00e0  d\u00e9sengorger les magasins et multiplier les convois vers le grand Kasai et le reste du r\u00e9seau.<br \/>\n Fabien Mutomb Kan kato s&#8217;est rendu ce mardi 7 mars <a href=\"https:\/\/www.snccsa.com\/wp-content\/uploads\/2023\/03\/Videoframe_20230307_164256_com.huawei.himovie.overseas.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.snccsa.com\/wp-content\/uploads\/2023\/03\/Videoframe_20230307_164256_com.huawei.himovie.overseas-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" class=\"aligncenter size-medium wp-image-67650\" \/><\/a>aux magasins pour palper du doigt le chargement de la rame de train marchandises destin\u00e9es \u00e0 Kananga. Les appros livrent incessamment le deuxi\u00e8me lot de b\u00e2ches et cordes pour permettre le b\u00e2chage et l&#8217;arrimage des wagons d\u00e9j\u00e0 charg\u00e9s. Le DG Fabien Mutomb  a fait le tour des magasins en compagnie du Directeur Commercial ai ,M. Tshijik Mwandashi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il est bon que toute rame de trains marchandises soit d\u00e9sormais reconnue par la qualit\u00e9 de b\u00e2ches dont les wagons sont couverts \u00e0 savoir b\u00e2ches de couleur Bleue, num\u00e9rot\u00e9s et avec logo SNCC en blanc. Comme voulu par le Directeur G\u00e9n\u00e9ral de la SNCC , M. Fabien Mutomb Kan kato, ces b\u00e2ches l\u00e0 sont d\u00e9j\u00e0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":67650,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-67649","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/posts\/67649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/comments?post=67649"}],"version-history":[{"count":7,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/posts\/67649\/revisions"}],"predecessor-version":[{"id":67668,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/posts\/67649\/revisions\/67668"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/media\/67650"}],"wp:attachment":[{"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/media?parent=67649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/categories?post=67649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/tags?post=67649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}