{"id":77539,"date":"2023-06-17T21:31:23","date_gmt":"2023-06-17T19:31:23","guid":{"rendered":"https:\/\/www.snccsa.com\/en\/?p=77539"},"modified":"2023-06-18T06:40:21","modified_gmt":"2023-06-18T04:40:21","slug":"sncc-regideso-volonte-manifeste-dameliorer-les-relations-daffaires","status":"publish","type":"post","link":"https:\/\/www.snccsa.com\/en\/2023\/06\/17\/sncc-regideso-volonte-manifeste-dameliorer-les-relations-daffaires\/","title":{"rendered":"SNCC-REGIDESO: volont\u00e9 manifeste d&#8217;am\u00e9liorer les relations d&#8217;affaires"},"content":{"rendered":"<p>La journ\u00e9e de travail du DG de la SNCC.SA, M. Fabien MUTOMB Kan kato a \u00e9t\u00e9 marqu\u00e9e ce vendredi 16 juin par la visite que son homologue de la REGIDESO, M. DAVID TSHILUMBA MUTOMBO  lui a rendue. Cette visite a donn\u00e9 lieu \u00e0 un \u00e9change franc sur le projet d&#8217;approvisionnement des cit\u00e9s de la SNCC.SA en eau potable , mais aussi sur la volont\u00e9 manifeste de la DG du g\u00e9ant de transport multimodal de honorer voire d&#8217;apurer la cr\u00e9ance due \u00e0 la r\u00e9gie de distribution des eaux.<br \/>\nLe Dga de la SNCC.SA, M. Jacques kamenga tshimuanga a particip\u00e9 \u00e0 cet \u00e9change qui s&#8217;est d\u00e9roul\u00e9 en deux temps, d&#8217;abord en appart\u00e9 dans le bureau du num\u00e9ro un de la SNCC.SA, et ensuite au salon vert,o\u00f9 les deux personnalit\u00e9s ont \u00e9t\u00e9 rejointes par leurs collaborateurs,comme notamment le directeur financier de la soci\u00e9t\u00e9 nationale des chemins de fer du Congo, M. Baudoin Hamisi bin kabarhuza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La journ\u00e9e de travail du DG de la SNCC.SA, M. Fabien MUTOMB Kan kato a \u00e9t\u00e9 marqu\u00e9e ce vendredi 16 juin par la visite que son homologue de la REGIDESO, M. DAVID TSHILUMBA MUTOMBO lui a rendue. Cette visite a donn\u00e9 lieu \u00e0 un \u00e9change franc sur le projet d&#8217;approvisionnement des cit\u00e9s de la SNCC.SA [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-77539","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/posts\/77539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/comments?post=77539"}],"version-history":[{"count":5,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/posts\/77539\/revisions"}],"predecessor-version":[{"id":77546,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/posts\/77539\/revisions\/77546"}],"wp:attachment":[{"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/media?parent=77539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/categories?post=77539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/tags?post=77539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}