{"id":77556,"date":"2023-06-21T10:49:27","date_gmt":"2023-06-21T08:49:27","guid":{"rendered":"https:\/\/www.snccsa.com\/en\/?p=77556"},"modified":"2023-06-23T06:23:25","modified_gmt":"2023-06-23T04:23:25","slug":"sncc-droit-de-passage-reload-logistics-sengage","status":"publish","type":"post","link":"https:\/\/www.snccsa.com\/en\/2023\/06\/21\/sncc-droit-de-passage-reload-logistics-sengage\/","title":{"rendered":"SNCC :Droit de passage, RELOAD LOGISTICS s&#8217;engage"},"content":{"rendered":"<p>RELOAD LOGISTICS s&#8217;engage \u00e0 op\u00e9rer sur le r\u00e9seau SNCC.SA dans le cadre d&#8217;une convention sur le droit de passage. Celle-ci a \u00e9t\u00e9 sign\u00e9e mardi 20 juin par le Dg Fabien Mutomb Kan kato pour le compte de la SNCC.SA, tandis que la RELOAD LOGISTICS \u00e9tait repr\u00e9sent\u00e9e par son g\u00e9rant, M. Mohamad WHEBI.<br \/>\nLe Dga Jacques kamenga tshimuanga a assist\u00e9 \u00e0 cette c\u00e9r\u00e9monie. Le Dg a associ\u00e9 \u00e0 la rencontre le Conseiller \u00e0 la Dg et les directeurs qui ont concouru \u00e0 l&#8217;\u00e9laboration de la convention, la neuvi\u00e8me du genre depuis que la direction g\u00e9n\u00e9rale de la SNCC.SA a instaur\u00e9 le droit de passage sur le r\u00e9seau de la soci\u00e9t\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RELOAD LOGISTICS s&#8217;engage \u00e0 op\u00e9rer sur le r\u00e9seau SNCC.SA dans le cadre d&#8217;une convention sur le droit de passage. Celle-ci a \u00e9t\u00e9 sign\u00e9e mardi 20 juin par le Dg Fabien Mutomb Kan kato pour le compte de la SNCC.SA, tandis que la RELOAD LOGISTICS \u00e9tait repr\u00e9sent\u00e9e par son g\u00e9rant, M. Mohamad WHEBI. Le Dga Jacques [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-77556","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/posts\/77556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/comments?post=77556"}],"version-history":[{"count":3,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/posts\/77556\/revisions"}],"predecessor-version":[{"id":77566,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/posts\/77556\/revisions\/77566"}],"wp:attachment":[{"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/media?parent=77556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/categories?post=77556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/tags?post=77556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}