{"id":77604,"date":"2023-06-27T14:38:37","date_gmt":"2023-06-27T12:38:37","guid":{"rendered":"https:\/\/www.snccsa.com\/en\/?p=77604"},"modified":"2023-06-30T16:17:37","modified_gmt":"2023-06-30T14:17:37","slug":"sncc-voici-la-composition-du-bureau-de-la-delegation-syndicale-nationale","status":"publish","type":"post","link":"https:\/\/www.snccsa.com\/en\/2023\/06\/27\/sncc-voici-la-composition-du-bureau-de-la-delegation-syndicale-nationale\/","title":{"rendered":"Sncc, voici la composition du bureau de la d\u00e9l\u00e9gation syndicale nationale"},"content":{"rendered":"<p><a href=\"https:\/\/www.snccsa.com\/wp-content\/uploads\/2023\/06\/DSC_3991-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.snccsa.com\/wp-content\/uploads\/2023\/06\/DSC_3991-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" class=\"aligncenter size-medium wp-image-77621\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.snccsa.com\/wp-content\/uploads\/2023\/06\/DSC_4326-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.snccsa.com\/wp-content\/uploads\/2023\/06\/DSC_4326-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" class=\"aligncenter size-medium wp-image-77622\" \/><\/a><br \/>\nLe nouveau bureau de la d\u00e9l\u00e9gation syndicale nationale de la SNCC.SA est pr\u00e9sid\u00e9 par le camarade SAFILA MAKANINO tandis que M. LUMBALA ILUNGA en est le secr\u00e9taire et M. NSUGU KASONGO, le secr\u00e9taire adjoint .<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td class=\"diff-addedline\"><span class=\"screen-reader-text\">Ajout\u00e9\u00a0: <\/span>Ce bureau compte 5 vice-pr\u00e9sidents \u00e0 savoir :1er vice-pr\u00e9sident : TShibondo katanda,<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td class=\"diff-addedline\"><span class=\"screen-reader-text\">Ajout\u00e9\u00a0: <\/span>2\u00e8me vice-pr\u00e9sident:kajingu Bibeji,<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td class=\"diff-addedline\"><span class=\"screen-reader-text\">Ajout\u00e9\u00a0: <\/span>3\u00e8me vice-pr\u00e9sident : Mukalayi Lembe,<\/td>\n<\/tr>\n<tr>\n<td class=\"diff-deletedline\"><span class=\"screen-reader-text\">Supprim\u00e9\u00a0! <\/span><\/td>\n<td class=\"diff-addedline\"><span class=\"screen-reader-text\">Ajout\u00e9\u00a0: <\/span>4\u00e8me vice-pr\u00e9sident :Umba ILUNGA ,<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td class=\"diff-addedline\"><span class=\"screen-reader-text\">Ajout\u00e9\u00a0: <\/span>5\u00e8me vice-pr\u00e9sident :Banza Mukalayi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le nouveau bureau de la d\u00e9l\u00e9gation syndicale nationale de la SNCC.SA est pr\u00e9sid\u00e9 par le camarade SAFILA MAKANINO tandis que M. LUMBALA ILUNGA en est le secr\u00e9taire et M. NSUGU KASONGO, le secr\u00e9taire adjoint . Ajout\u00e9\u00a0: Ce bureau compte 5 vice-pr\u00e9sidents \u00e0 savoir :1er vice-pr\u00e9sident : TShibondo katanda, Ajout\u00e9\u00a0: 2\u00e8me vice-pr\u00e9sident:kajingu Bibeji, Ajout\u00e9\u00a0: 3\u00e8me vice-pr\u00e9sident [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":77622,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p>Le nouveau bureau de la d\u00e9l\u00e9gation syndicale nationale de la SNCC.SA est pr\u00e9sid\u00e9 par le camarade SAFILA MAKANINO tandis que M. LUMBALA ILUNGA en est le secr\u00e9taire et M. NSUGU KASONGO, le secr\u00e9taire adjoint .<\/p><p>Ce bureau compte 5 vice-pr\u00e9sidents \u00e0 savoir :1er vice-pr\u00e9sident : TShibondo katanda,<\/p><p>2\u00e8me vice-pr\u00e9sident:kajingu Bibeji,<\/p><p>3\u00e8me vice-pr\u00e9sident : Mukalayi Lembe,<\/p><p>4\u00e8me vice-pr\u00e9sident :Umba ILUNGA ,<\/p><p>5\u00e8me vice-pr\u00e9sident :Banza Mukalayi.<\/p>","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-77604","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/posts\/77604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/comments?post=77604"}],"version-history":[{"count":12,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/posts\/77604\/revisions"}],"predecessor-version":[{"id":77659,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/posts\/77604\/revisions\/77659"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/media\/77622"}],"wp:attachment":[{"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/media?parent=77604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/categories?post=77604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/tags?post=77604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}