{"id":77676,"date":"2023-07-03T10:05:15","date_gmt":"2023-07-03T08:05:15","guid":{"rendered":"https:\/\/www.snccsa.com\/en\/?p=77676"},"modified":"2023-07-07T06:15:23","modified_gmt":"2023-07-07T04:15:23","slug":"sncc-mobirail-programme-le-train-kambelembele-le-25-juillet-prochain","status":"publish","type":"post","link":"https:\/\/www.snccsa.com\/en\/2023\/07\/03\/sncc-mobirail-programme-le-train-kambelembele-le-25-juillet-prochain\/","title":{"rendered":"SNCC :MOBIRAIL programme le train KAMBELEMBELE le 25 juillet prochain"},"content":{"rendered":"<p>Mobirail organise les trains ci-apr\u00e8s pour juillet 2023:<br \/>\n1. TRAINS EXPRESS au d\u00e9part de lubumbashi<br \/>\n-5 juillet : Train New Express colombe \u00e0 destination de kananga,<br \/>\n-19 juillet : Train New Express Diamant Beton \u00e0 destination de MWENE ditu.<br \/>\n2. TRAIN ORDINAIRE LONG COURRIER partant de lubumbashi<br \/>\n-25 juillet :Train KAMBELEMBELE \u00e0 destination de kindu.<br \/>\n3. TRAINS INTER- REGIONS<br \/>\n-12 et 26 juillet:Train SANKAYI de kananga \u00e0 ilebo,<br \/>\n-15 juillet :Train YALISANO de kolwezi \u00e0 Dilolo,<br \/>\n-18 juillet :Train SERPENT de rail de kalemie \u00e0 kindu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mobirail organise les trains ci-apr\u00e8s pour juillet 2023: 1. TRAINS EXPRESS au d\u00e9part de lubumbashi -5 juillet : Train New Express colombe \u00e0 destination de kananga, -19 juillet : Train New Express Diamant Beton \u00e0 destination de MWENE ditu. 2. TRAIN ORDINAIRE LONG COURRIER partant de lubumbashi -25 juillet :Train KAMBELEMBELE \u00e0 destination de kindu. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-77676","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/posts\/77676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/comments?post=77676"}],"version-history":[{"count":7,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/posts\/77676\/revisions"}],"predecessor-version":[{"id":77687,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/posts\/77676\/revisions\/77687"}],"wp:attachment":[{"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/media?parent=77676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/categories?post=77676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/tags?post=77676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}