{"id":78430,"date":"2024-03-22T12:46:30","date_gmt":"2024-03-22T10:46:30","guid":{"rendered":"https:\/\/www.snccsa.com\/en\/?p=78430"},"modified":"2024-05-02T10:03:42","modified_gmt":"2024-05-02T08:03:42","slug":"snccc-dotation-en-locomotives-et-vedettes-pour-booster-sa-capacite-de-transport","status":"publish","type":"post","link":"https:\/\/www.snccsa.com\/en\/2024\/03\/22\/snccc-dotation-en-locomotives-et-vedettes-pour-booster-sa-capacite-de-transport\/","title":{"rendered":"SNCCC: dotation en locomotives et vedettes pour  booster sa capacit\u00e9 de transport"},"content":{"rendered":"<p>Longtemps consid\u00e9r\u00e9e comme un canard boiteux, la SNCC sous le leadership de Fabien Mutomb kan kato , son directeur g\u00e9n\u00e9ral, est actuellement dans la phase de redressement , soutenu par un programme initi\u00e9 par le Chef de l\u2019Etat , SE F\u00e9lix Antoine TSHISEKEDI TSHILOMBO, \u00e0 la lumi\u00e8re de sa vision d\u2019un Chemin de Fer moderne au c\u0153ur de l\u2019Afrique.<\/p>\n<p>C\u2019est dans ce contexte qu\u2019il sied d\u00e9pingler le programme , sur fonds de la RLT, g\u00e9r\u00e9 par le Minist\u00e8re des transports, Voies de Communication et D\u00e9senclavement,  et celui des finances, programme destin\u00e9 aux investissements pour l\u2019acquisition et la r\u00e9habilitation de l\u2019outil de production de la SNCC afin de l\u2019aider \u00e0 jouer efficacement son r\u00f4le d\u2019\u00e9pine dorsale de l\u2019\u00e9conomie nationale et de fer de lance de la lutte contre la pauvret\u00e9.<\/p>\n<p>Ce programme s\u2019est d\u00e9j\u00e0 concr\u00e9tis\u00e9 et continue \u00e0 l\u2019\u00eatre, \u00e0 travers, sans \u00eatre exhaustif, les acquisitions ci-apr\u00e8s :<br \/>\n&#8211;\t100 portes conteneurs neufs en juin 2023,<br \/>\n&#8211;\t4 vedettes rapides de ligne pour la relance du trafic lacustre sur le lac Kivu, dont l\u2019inauguration a eu lieu le 09 janvier dernier par Son Excellence Monsieur le Chef de l\u2019Etat,<br \/>\n&#8211;\t2 (deux) locomotives d\u2019occasion, r\u00e9habilit\u00e9es et modernis\u00e9es, sur une commande de 08,<br \/>\n&#8211;\t5 locomotives neuves sur un lot de 10 attendues, et dont la remise officielle a eu lieu par Son Excellence Monsieur le Ministre des Transports, Voies de Communication et D\u00e9senclavement,  Marc EKILA LIKOMBO, le 11 mars dernier.<\/p>\n<p>Comme r\u00e9alisations au profit de la SNCC, on signale \u00e9galement la remotorisation du bateau LOKANDO qui op\u00e8re sur le bief moyen du fleuve Congo entre Kindu-Ubundu, \u00e0 la grande satisfaction des riverains du fleuve ; ceci a permis \u00e0 la SNCC de contribuer au d\u00e9senclavement des provinces du Maniema et de la Tshopo.<\/p>\n<p>Ce sont l\u00e0 les r\u00e9alisations visant \u00e0 accroitre la capacit\u00e9 de traction et de transport de la SNCC par rail, lac et fleuve.<\/p>\n<p>A ceci , s&#8217;ajoutent d&#8217;autres r\u00e9alisations pour la r\u00e9habilitation de la voie ferr\u00e9e. Il s\u2019agit des travaux du renouvellement de la voie sur 19 Km sur le tron\u00e7on Lufupa-Kanzenze, de l\u2019acquisition de 70.000 traverses m\u00e9talliques neuves et de 8.800 tonnes de rails en cours d\u2019acheminement.<\/p>\n<p>Occasion pour le Manager du chemin de fer de saluer cette acquisition qui permet \u00e0 la soci\u00e9t\u00e9 de satisfaire sa client\u00e8le. <\/p>\n<p>Les 5 locomotives de la s\u00e9rie 1800 pr\u00e9sentent des caract\u00e9ristiques adapt\u00e9es au profil de la voie de la SNCC qui s\u2019\u00e9tend sur 3.641 Km et dessert 12 des 26 provinces de la RDC. A savoir poids : 90 Tonnes, moteur de 12 cylindres, contr\u00f4le \u00e9lectronique par microprocesseur. Capacit\u00e9 de traction d\u2019une charge allant jusqu\u2019\u00e0 20.000 Tonnes.     <\/p>\n<p>Cette acquisition  apporte un ouf de soulagement dans l\u2019exploitation des trains et permet d\u2019am\u00e9liorer leur d\u00e9serte aussi bien pour le trafic des marchandises que pour le trafic voyageurs.<\/p>\n<p>Si Fabien Mutomb Kan Kato et son staff ont r\u00e9ussi \u00e0 se donner les moyens de traction, il reste un d\u00e9fi \u00e0 relever s\u2019agissant de la voie ferr\u00e9e dont l\u2019\u00e9tat laisse \u00e0 d\u00e9sirer sur certains secteurs. Cela dit, Fabien Mutomb n\u2019a pas attendu l\u2019arriv\u00e9e de locomotives neuves pour s\u2019attaquer au dossier \u2018\u2019Voie\u2019\u2019.<\/p>\n<p>En effet, apr\u00e8s le renouvellement de 16 Km du tron\u00e7on Lufupa \u2013 Kanzenze, plus 3 Km entre Lufupa-Lungenda, sur l\u2019axe Kolwezi-Dilolo, la Direction G\u00e9n\u00e9rale SNCC a consenti des investissements pour approvisionnement en traverses, rails et autres mat\u00e9riels de voie en vue de lancer de gros travaux de voie sur les sections les plus abim\u00e9es soit plus de la moiti\u00e9 de 3641 Km de son r\u00e9seau (DIF). <\/p>\n<p>Plus de 11.000 sur les 30.000 traverses m\u00e9talliques achet\u00e9es sur fonds de la RLT sont d\u00e9j\u00e0 disponibles au site de l\u2019\u00e9tincelage au quartier industriel \u00e0 Lubumbashi. 20.000 autres sont attendues dans le cadre du pr\u00e9financement consenti par le partenaire IMPALA pour le renouvellement de 61 Km entre Lufupa-Dilolo.<\/p>\n<p>Plus de 20.000 traverses ont \u00e9t\u00e9 utilis\u00e9es lors de travaux de renouvellement \u00e0 Lufupa-Kolwezi. En outre, 8.800 tonnes de rail sont en cours d\u2019acheminement sur fond de la RLT.<\/p>\n<p>Toujours sur financement de la RLT, une nouvelle ligne de concassage a \u00e9t\u00e9 acquise pour la carri\u00e8re de Lusindoie \u00e0 Kongolo. Les carri\u00e8res de Kakopa, (Lualaba), de Kaniama (Lomami) et de la Nganza (Kasa\u00ef Central) font \u00e9galement l\u2019objet d\u2019un grand int\u00e9r\u00eat de la Direction G\u00e9n\u00e9rale en tant que sources d\u2019approvisionnement et de transformation du ballast, mat\u00e9riau essentiel dans la construction et le renouvellement du chemin de fer.<\/p>\n<p>Pour la carri\u00e8re de Kakopa, la SNCC  envisage d\u2019acqu\u00e9rir sur fonds de la Redevance Logistique Terrestre (RLT), un lot d\u2019engins roulant d\u2019excavation, de manutention et de sondage.<\/p>\n<p>Il s\u2019agit de pelle chargeuse, bulldozer, camion benne, chargeuse m\u00e9canique ainsi que de pi\u00e8ces de rechange. <\/p>\n<p>Elle entend \u00e9galement acqu\u00e9rir des pi\u00e8ces de rechange des engins lourds de la voie (Bourreuse, R\u00e9galeuse, Degarnisseuse\u2026\u2026\u2026\u2026.), des kits de soudure aluminothermique pour rails de type BCK 29 Kg\/m et 40 Kg\/m. du sable et graviers pour la fabrication des traverses en b\u00e9ton arm\u00e9 bi bloc.<br \/>\n&#8211;\tDes outillages manuels et des petits engins de voie<br \/>\n&#8211;\tDes engins roulants d\u2019excavation de manutention et de soudage  \u00e0 la carri\u00e8re de Lusindoie<br \/>\n&#8211;\tAcquisition d\u2019une r\u00e9galeuse neuve r\u00e9 profileuse de ballast.   <\/p>\n<p>Face aux \u00e9rosions qui menacent la voie, il est pr\u00e9vu, dans le cadre des investissements financ\u00e9s par la RLT, la dotation de chaque R\u00e9gion d\u2019exploitation de la SNCC, d\u2019un atelier m\u00e9canis\u00e9 compos\u00e9 d\u2019engins lourds de G\u00e9nie Civil.<\/p>\n<p>Il est \u00e9galement pr\u00e9vu des travaux de maintenance et de d\u00e9sherbage de la voie pour permettre une meilleure fluidit\u00e9 du trafic.<\/p>\n<p>Outre des investissements en terme de mat\u00e9riel, il y a lieu de noter \u00e9galement les efforts d\u00e9ploy\u00e9s sur le chapitre des Ressources Humaines dont le rajeunissement demeure le cheval de bataille de la Direction G\u00e9n\u00e9rale dans le processus de redressement de la SNCC.<\/p>\n<p>Dans cet ordre d\u2019id\u00e9e, on peut souligner notamment le recrutement de 50 agents de la voie d\u2019abord, puis de 250 avant d\u2019engager 200 autres pour les secteurs Techniques.<\/p>\n<p>Sans oublier le plan de mise en retraite qui attend l\u2019aval du Conseil d\u2019Administration  avant son ex\u00e9cution.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Longtemps consid\u00e9r\u00e9e comme un canard boiteux, la SNCC sous le leadership de Fabien Mutomb kan kato , son directeur g\u00e9n\u00e9ral, est actuellement dans la phase de redressement , soutenu par un programme initi\u00e9 par le Chef de l\u2019Etat , SE F\u00e9lix Antoine TSHISEKEDI TSHILOMBO, \u00e0 la lumi\u00e8re de sa vision d\u2019un Chemin de Fer moderne [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-78430","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/posts\/78430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/comments?post=78430"}],"version-history":[{"count":4,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/posts\/78430\/revisions"}],"predecessor-version":[{"id":78460,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/posts\/78430\/revisions\/78460"}],"wp:attachment":[{"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/media?parent=78430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/categories?post=78430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.snccsa.com\/en\/wp-json\/wp\/v2\/tags?post=78430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}